{"id":9809,"date":"2026-02-19T10:43:42","date_gmt":"2026-02-19T10:43:42","guid":{"rendered":"https:\/\/trackcable.com\/product\/supports-de-fixation-ua-1665-075\/"},"modified":"2026-03-26T13:58:53","modified_gmt":"2026-03-26T13:58:53","slug":"supports-de-fixation-ua-1665-075","status":"publish","type":"product","link":"https:\/\/trackcable.com\/fr\/produit\/supports-de-fixation-ua-1665-075\/","title":{"rendered":"Supports de fixation \u2013 UA 1665-075"},"content":{"rendered":"<p data-start=\"0\" data-end=\"394\"><strong data-start=\"0\" data-end=\"80\">Les supports de montage TSUBAKI KABELSCHLEPP pour l\u2019Uniflex Advanced 1665-075<\/strong> assurent une connexion s\u00fbre et pr\u00e9cise entre les cha\u00eenes porte-c\u00e2ble et la structure de la machine. Sp\u00e9cialement con\u00e7us pour la s\u00e9rie Uniflex Advanced de <span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">TSUBAKI KABELSCHLEPP<\/span><\/span>, ces supports garantissent un ajustement pr\u00e9cis tout en assurant un fonctionnement stable et fiable dans des environnements industriels dynamiques. <\/p>\n<p data-start=\"396\" data-end=\"747\">Con\u00e7us pour des cha\u00eenes porte-c\u00e2ble avec une <strong data-start=\"431\" data-end=\"452\">largeur int\u00e9rieure de 75 mm<\/strong>, ces supports de montage aident \u00e0 maintenir un alignement correct dans tout le syst\u00e8me, r\u00e9duisant les contraintes m\u00e9caniques et contribuant \u00e0 un mouvement plus fluide de la cha\u00eene. Leur construction robuste les rend parfaitement adapt\u00e9s aux machines automatis\u00e9es, o\u00f9 des performances constantes et une durabilit\u00e9 \u00e0 long terme sont essentielles. <\/p>\n<p data-start=\"749\" data-end=\"996\">Enti\u00e8rement compatibles avec l\u2019<strong data-start=\"775\" data-end=\"804\">Uniflex Advanced 1665-075<\/strong>, ces supports permettent une installation rapide et cr\u00e9ent une interface fiable entre les cha\u00eenes porte-c\u00e2ble et le b\u00e2ti de la machine, contribuant \u00e0 optimiser la dur\u00e9e de vie globale du syst\u00e8me de gestion des c\u00e2bles.<\/p>\n<h3 data-start=\"998\" data-end=\"1014\">Caract\u00e9ristiques cl\u00e9s<\/h3>\n<ul data-start=\"1016\" data-end=\"1335\">\n<li data-start=\"1016\" data-end=\"1104\">\n<p data-start=\"1018\" data-end=\"1104\">Con\u00e7us pour les cha\u00eenes porte-c\u00e2ble <strong data-start=\"1031\" data-end=\"1060\">Uniflex Advanced 1665-075<\/strong> avec une <strong data-start=\"1081\" data-end=\"1102\">largeur int\u00e9rieure de 75 mm<\/strong><\/p>\n<\/li>\n<li data-start=\"1105\" data-end=\"1167\">\n<p data-start=\"1107\" data-end=\"1167\">Assure un montage s\u00fbr et stable dans des applications dynamiques<\/p>\n<\/li>\n<li data-start=\"1168\" data-end=\"1230\">\n<p data-start=\"1170\" data-end=\"1230\">Assure un alignement pr\u00e9cis pour une exploitation fiable du porte-avions<\/p>\n<\/li>\n<li data-start=\"1231\" data-end=\"1272\">\n<p data-start=\"1233\" data-end=\"1272\">Installation rapide et simple<\/p>\n<\/li>\n<li data-start=\"1273\" data-end=\"1335\">\n<p data-start=\"1275\" data-end=\"1335\">Construction durable pour des environnements industriels exigeants<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"1337\" data-end=\"1574\" data-is-last-node=\"\" data-is-only-node=\"\">Les <strong data-start=\"1341\" data-end=\"1388\">supports de montage Uniflex Advanced 1665-075<\/strong> sont un choix id\u00e9al pour les ing\u00e9nieurs et les constructeurs de machines \u00e0 la recherche d\u2019une solution de fixation fiable qui am\u00e9liore la stabilit\u00e9 du syst\u00e8me, simplifie l\u2019installation et soutient les performances \u00e0 long terme.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span style=\"font-size: 12px; line-height: 1.2; display: block;\"><br \/>\nSupports de fixation pour la s\u00e9rie UA 1665, largeur int\u00e9rieure 075 mm.<br \/>\n<\/span><\/p>\n","protected":false},"featured_media":8957,"comment_status":"open","ping_status":"closed","template":"","meta":[],"etheme_brands":[{"term_id":702,"name":"Tsubaki Kabelschlepp","slug":"tsubaki-kabelschlepp","term_group":0,"term_taxonomy_id":702,"taxonomy":"brand","description":"Tsubaki Kabelschlepp est un fournisseur mondialement reconnu de syst\u00e8mes de cha\u00eenes porte-c\u00e2bles et de guidage, offrant des solutions robustes et con\u00e7ues avec pr\u00e9cision pour guider et prot\u00e9ger les c\u00e2bles dans des applications industrielles dynamiques.","parent":0,"count":192,"filter":"raw"}],"product_brand":[],"product_cat":[306],"product_tag":[],"class_list":{"0":"post-9809","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"brand-tsubaki-kabelschlepp","7":"product_cat-supports-de-montage","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Supports de montage Kabelschlepp UA 1665-075 | TrackCable<\/title>\n<meta name=\"description\" content=\"Achetez des supports de montage Kabelschlepp UA 1665-075 pour une installation s\u00e9curis\u00e9e des cha\u00eenes porte-c\u00e2ble dans les applications industrielles. Livraison rapide disponible.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/trackcable.com\/fr\/produit\/supports-de-fixation-ua-1665-075\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Supports de montage Kabelschlepp UA 1665-075 | TrackCable\" \/>\n<meta property=\"og:description\" content=\"Achetez des supports de montage Kabelschlepp UA 1665-075 pour une installation s\u00e9curis\u00e9e des cha\u00eenes porte-c\u00e2ble dans les applications industrielles. Livraison rapide disponible.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/trackcable.com\/fr\/produit\/supports-de-fixation-ua-1665-075\/\" \/>\n<meta property=\"og:site_name\" content=\"trackcable.com\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-26T13:58:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/trackcable.com\/wp-content\/uploads\/2026\/02\/1455-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"199\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/trackcable.com\\\/fr\\\/produit\\\/supports-de-fixation-ua-1665-075\\\/\",\"url\":\"https:\\\/\\\/trackcable.com\\\/fr\\\/produit\\\/supports-de-fixation-ua-1665-075\\\/\",\"name\":\"Supports de montage Kabelschlepp UA 1665-075 | TrackCable\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/trackcable.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/trackcable.com\\\/fr\\\/produit\\\/supports-de-fixation-ua-1665-075\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/trackcable.com\\\/fr\\\/produit\\\/supports-de-fixation-ua-1665-075\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/trackcable.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/1455-1.jpg\",\"datePublished\":\"2026-02-19T10:43:42+00:00\",\"dateModified\":\"2026-03-26T13:58:53+00:00\",\"description\":\"Achetez des supports de montage Kabelschlepp UA 1665-075 pour une installation s\u00e9curis\u00e9e des cha\u00eenes porte-c\u00e2ble dans les applications industrielles. Livraison rapide disponible.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/trackcable.com\\\/fr\\\/produit\\\/supports-de-fixation-ua-1665-075\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/trackcable.com\\\/fr\\\/produit\\\/supports-de-fixation-ua-1665-075\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/trackcable.com\\\/fr\\\/produit\\\/supports-de-fixation-ua-1665-075\\\/#primaryimage\",\"url\":\"https:\\\/\\\/trackcable.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/1455-1.jpg\",\"contentUrl\":\"https:\\\/\\\/trackcable.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/1455-1.jpg\",\"width\":300,\"height\":199,\"caption\":\"Deux supports de montage noirs et gris - UA 1455-025 - sont affich\u00e9s c\u00f4te \u00e0 c\u00f4te, chacun avec deux trous sur la base et les c\u00f4t\u00e9s verticaux, pr\u00e9sentant des d\u00e9tails circulaires et encochonn\u00e9s.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/trackcable.com\\\/fr\\\/produit\\\/supports-de-fixation-ua-1665-075\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/trackcable.com\\\/fr\\\/accueil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\\\/\\\/trackcable.com\\\/fr\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Supports de fixation \u2013 UA 1665-075\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/trackcable.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/trackcable.com\\\/fr\\\/\",\"name\":\"trackcable.com\",\"description\":\"Precision in cable management\",\"publisher\":{\"@id\":\"https:\\\/\\\/trackcable.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/trackcable.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/trackcable.com\\\/fr\\\/#organization\",\"name\":\"TrackCable | Precision in industrial cable management\",\"url\":\"https:\\\/\\\/trackcable.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/trackcable.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/trackcable.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/TrackCable.jpg\",\"contentUrl\":\"https:\\\/\\\/trackcable.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/TrackCable.jpg\",\"width\":600,\"height\":300,\"caption\":\"TrackCable | Precision in industrial cable management\"},\"image\":{\"@id\":\"https:\\\/\\\/trackcable.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Supports de montage Kabelschlepp UA 1665-075 | TrackCable","description":"Achetez des supports de montage Kabelschlepp UA 1665-075 pour une installation s\u00e9curis\u00e9e des cha\u00eenes porte-c\u00e2ble dans les applications industrielles. Livraison rapide disponible.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/trackcable.com\/fr\/produit\/supports-de-fixation-ua-1665-075\/","og_locale":"fr_FR","og_type":"article","og_title":"Supports de montage Kabelschlepp UA 1665-075 | TrackCable","og_description":"Achetez des supports de montage Kabelschlepp UA 1665-075 pour une installation s\u00e9curis\u00e9e des cha\u00eenes porte-c\u00e2ble dans les applications industrielles. Livraison rapide disponible.","og_url":"https:\/\/trackcable.com\/fr\/produit\/supports-de-fixation-ua-1665-075\/","og_site_name":"trackcable.com","article_modified_time":"2026-03-26T13:58:53+00:00","og_image":[{"width":300,"height":199,"url":"https:\/\/trackcable.com\/wp-content\/uploads\/2026\/02\/1455-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/trackcable.com\/fr\/produit\/supports-de-fixation-ua-1665-075\/","url":"https:\/\/trackcable.com\/fr\/produit\/supports-de-fixation-ua-1665-075\/","name":"Supports de montage Kabelschlepp UA 1665-075 | TrackCable","isPartOf":{"@id":"https:\/\/trackcable.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/trackcable.com\/fr\/produit\/supports-de-fixation-ua-1665-075\/#primaryimage"},"image":{"@id":"https:\/\/trackcable.com\/fr\/produit\/supports-de-fixation-ua-1665-075\/#primaryimage"},"thumbnailUrl":"https:\/\/trackcable.com\/wp-content\/uploads\/2026\/02\/1455-1.jpg","datePublished":"2026-02-19T10:43:42+00:00","dateModified":"2026-03-26T13:58:53+00:00","description":"Achetez des supports de montage Kabelschlepp UA 1665-075 pour une installation s\u00e9curis\u00e9e des cha\u00eenes porte-c\u00e2ble dans les applications industrielles. Livraison rapide disponible.","breadcrumb":{"@id":"https:\/\/trackcable.com\/fr\/produit\/supports-de-fixation-ua-1665-075\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/trackcable.com\/fr\/produit\/supports-de-fixation-ua-1665-075\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/trackcable.com\/fr\/produit\/supports-de-fixation-ua-1665-075\/#primaryimage","url":"https:\/\/trackcable.com\/wp-content\/uploads\/2026\/02\/1455-1.jpg","contentUrl":"https:\/\/trackcable.com\/wp-content\/uploads\/2026\/02\/1455-1.jpg","width":300,"height":199,"caption":"Deux supports de montage noirs et gris - UA 1455-025 - sont affich\u00e9s c\u00f4te \u00e0 c\u00f4te, chacun avec deux trous sur la base et les c\u00f4t\u00e9s verticaux, pr\u00e9sentant des d\u00e9tails circulaires et encochonn\u00e9s."},{"@type":"BreadcrumbList","@id":"https:\/\/trackcable.com\/fr\/produit\/supports-de-fixation-ua-1665-075\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/trackcable.com\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/trackcable.com\/fr\/boutique\/"},{"@type":"ListItem","position":3,"name":"Supports de fixation \u2013 UA 1665-075"}]},{"@type":"WebSite","@id":"https:\/\/trackcable.com\/fr\/#website","url":"https:\/\/trackcable.com\/fr\/","name":"trackcable.com","description":"Precision in cable management","publisher":{"@id":"https:\/\/trackcable.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/trackcable.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/trackcable.com\/fr\/#organization","name":"TrackCable | Precision in industrial cable management","url":"https:\/\/trackcable.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/trackcable.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/trackcable.com\/wp-content\/uploads\/2026\/02\/TrackCable.jpg","contentUrl":"https:\/\/trackcable.com\/wp-content\/uploads\/2026\/02\/TrackCable.jpg","width":600,"height":300,"caption":"TrackCable | Precision in industrial cable management"},"image":{"@id":"https:\/\/trackcable.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/trackcable.com\/fr\/wp-json\/wp\/v2\/product\/9809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trackcable.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/trackcable.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/trackcable.com\/fr\/wp-json\/wp\/v2\/comments?post=9809"}],"version-history":[{"count":1,"href":"https:\/\/trackcable.com\/fr\/wp-json\/wp\/v2\/product\/9809\/revisions"}],"predecessor-version":[{"id":13457,"href":"https:\/\/trackcable.com\/fr\/wp-json\/wp\/v2\/product\/9809\/revisions\/13457"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trackcable.com\/fr\/wp-json\/wp\/v2\/media\/8957"}],"wp:attachment":[{"href":"https:\/\/trackcable.com\/fr\/wp-json\/wp\/v2\/media?parent=9809"}],"wp:term":[{"taxonomy":"brand","embeddable":true,"href":"https:\/\/trackcable.com\/fr\/wp-json\/wp\/v2\/etheme_brands?post=9809"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/trackcable.com\/fr\/wp-json\/wp\/v2\/product_brand?post=9809"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/trackcable.com\/fr\/wp-json\/wp\/v2\/product_cat?post=9809"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/trackcable.com\/fr\/wp-json\/wp\/v2\/product_tag?post=9809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}